{"id":5333,"date":"2024-01-02T22:02:20","date_gmt":"2024-01-03T01:02:20","guid":{"rendered":"http:\/\/superinteressantes.com.br\/index.php\/2024\/01\/02\/prefeitura-de-cuiab-equipe-promove-reunio-para-solucionar-problemas-deixados-pela-interveno-no-cdmic-falta-de-sistema-e-falhas-de-inventrio-j-foram-constatados\/"},"modified":"2024-01-02T22:02:20","modified_gmt":"2024-01-03T01:02:20","slug":"prefeitura-de-cuiab-equipe-promove-reunio-para-solucionar-problemas-deixados-pela-interveno-no-cdmic-falta-de-sistema-e-falhas-de-inventrio-j-foram-constatados","status":"publish","type":"post","link":"https:\/\/superinteressantes.com.br\/index.php\/2024\/01\/02\/prefeitura-de-cuiab-equipe-promove-reunio-para-solucionar-problemas-deixados-pela-interveno-no-cdmic-falta-de-sistema-e-falhas-de-inventrio-j-foram-constatados\/","title":{"rendered":"Prefeitura de Cuiab | Equipe promove reunio para solucionar problemas deixados pela Interveno no CDMIC; falta de sistema e falhas de inventrio j foram constatados"},"content":{"rendered":"<p><\/p>\n<div itemprop=\"articleBody\">\n<p>A equipe nomeada pelo prefeito Emanuel Pinheiro realizou nesta ter\u00e7a-feira reuni\u00e3o no Centro de Distribui\u00e7\u00e3o de Medicamentos e Insumos (CDMIC) visando encontrar solu\u00e7\u00f5es para problemas deixados pelo Gabinete de Interven\u00e7\u00e3o. A Prefeitura de Cuiab\u00e1 assumiu a sa\u00fade do munic\u00edpio na segunda-feira (1).<\/p>\n<p>Entre os problemas encontrados pela equipe liderada pelo especialista em Sa\u00fade, Oscarlino Alves, est\u00e3o aus\u00eancia do sistema LOG LAB para registro e sa\u00edda de medicamentos o que \u00e9 um problema para a gest\u00e3o refletindo nos usu\u00e1rios do Sistema \u00danico de Sa\u00fade (SUS), falta de empilhadeiras e pessoal qualificado para operar, falhas na realiza\u00e7\u00e3o do invent\u00e1rio de medicamentos, falta de pessoal especializado.<\/p>\n<p>Um dos problemas mais graves, a suspens\u00e3o do sistema\u00a0Sistema Integrado de Gest\u00e3o Hospitalar Controle e Dispensa\u00e7\u00e3o de Medicamentos da rede municipal de Sa\u00fade e da Empresa Cuiabana de Sa\u00fade P\u00fablica (ECSP)\u00a0provocou problemas no fluxo de trabalho dos servidores. Informa\u00e7\u00f5es coletadas pela equipe j\u00e1 denotam que a grave situa\u00e7\u00e3o persiste h\u00e1 mais de 30 dias e afeta a toda a rede municipal de Sa\u00fade.<\/p>\n<p>\u00a0Segundo Oscarlino Alves, o trabalho da equipe designada pelo prefeito Emanuel Pinheiro preenche uma lacuna deixada pelo Gabinete de Interven\u00e7\u00e3o: a falta de uma transi\u00e7\u00e3o adequada, com diagn\u00f3stico do que \u00e9 preciso avan\u00e7ar e quais s\u00e3o os problemas deixados.<\/p>\n<p>&#8220;Nesse exato momento, n\u00f3s estamos fazendo um levantamento operacional, de log\u00edstica, de medicamentos e de insumos&#8221;, afirmou Oscarlino. &#8220;Do jeito que a situa\u00e7\u00e3o est\u00e1 \u00e9 completamente imposs\u00edvel realizar o controle da sa\u00edda de medicamentos; sem o sistema suspenso por falta de pagamento, o servi\u00e7o \u00e9 completamente comprometido&#8221;, completou Oscarlino.<\/p>\n<p>Segundo Renaudt Tedesco de Carvalho, servidor efetivo da Prefeitura de Cuiab\u00e1 e integrante da equipe provis\u00f3ria, ser\u00e1 realizado um planejamento para solucionar os problemas, e o documento ser\u00e1 entregue ao prefeito Emanuel Pinheiro.<\/p>\n<p>&#8220;Fomos bem recebidos pelos servidores, todos eles \u00e9ticos e t\u00e9cnicos nas suas falas&#8221;, afirmou Renaudt. &#8220;N\u00e3o houve um plano de transi\u00e7\u00e3o para entregar esse servi\u00e7o; foi tudo feito de forma informal e \u00e0s pressas. N\u00e3o sabemos, por exemplo, por que esse sistema de informa\u00e7\u00e3o n\u00e3o est\u00e1 funcionando, e a gente precisa agora tra\u00e7ar um plano de conting\u00eancia e ver como vamos retomar esse servi\u00e7o&#8221;, completou.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A equipe nomeada pelo prefeito Emanuel Pinheiro realizou nesta ter\u00e7a-feira reuni\u00e3o no Centro de Distribui\u00e7\u00e3o de Medicamentos e Insumos (CDMIC) visando encontrar solu\u00e7\u00f5es para problemas deixados pelo Gabinete de Interven\u00e7\u00e3o. A Prefeitura de Cuiab\u00e1 assumiu a sa\u00fade do munic\u00edpio na segunda-feira (1). Entre os problemas encontrados pela equipe liderada pelo especialista em Sa\u00fade, Oscarlino Alves, &#8230; <a title=\"Prefeitura de Cuiab | Equipe promove reunio para solucionar problemas deixados pela Interveno no CDMIC; falta de sistema e falhas de inventrio j foram constatados\" class=\"read-more\" href=\"https:\/\/superinteressantes.com.br\/index.php\/2024\/01\/02\/prefeitura-de-cuiab-equipe-promove-reunio-para-solucionar-problemas-deixados-pela-interveno-no-cdmic-falta-de-sistema-e-falhas-de-inventrio-j-foram-constatados\/\" aria-label=\"More on Prefeitura de Cuiab | Equipe promove reunio para solucionar problemas deixados pela Interveno no CDMIC; falta de sistema e falhas de inventrio j foram constatados\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-5333","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5333"}],"version-history":[{"count":0,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5333\/revisions"}],"wp:attachment":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}