{"id":39937,"date":"2026-09-01T21:12:19","date_gmt":"2026-09-02T00:12:19","guid":{"rendered":"https:\/\/superinteressantes.com.br\/index.php\/2026\/09\/01\/ifsp-distribui-165-novos-codigos-de-vaga-para-docentes-entre-os-campi-ifsp\/"},"modified":"2026-09-01T21:12:19","modified_gmt":"2026-09-02T00:12:19","slug":"ifsp-distribui-165-novos-codigos-de-vaga-para-docentes-entre-os-campi-ifsp","status":"publish","type":"post","link":"https:\/\/superinteressantes.com.br\/index.php\/2026\/09\/01\/ifsp-distribui-165-novos-codigos-de-vaga-para-docentes-entre-os-campi-ifsp\/","title":{"rendered":"IFSP distribui 165 novos c\u00f3digos de vaga para docentes entre os campi &#8211; IFSP"},"content":{"rendered":"<p><\/p>\n<div>\n<div class=\"subtitle\">\n<p>Distribui\u00e7\u00e3o considera as necessidades previstas no Plano de Desenvolvimento Institucional; confira o\u00a0comunicado n\u00b0 22\/2026<\/p>\n<\/div>\n<p><!-- fim .content-header-options-1 --><\/p>\n<p>O Instituto Federal de S\u00e3o Paulo (IFSP) iniciou a distribui\u00e7\u00e3o de novos c\u00f3digos de vaga para o cargo de Professor do Ensino B\u00e1sico, T\u00e9cnico e Tecnol\u00f3gico (EBTT). Ao todo, a institui\u00e7\u00e3o recebeu 180 novos c\u00f3digos por meio da Portaria MEC n\u00ba 657\/2026, dos quais 165 ser\u00e3o destinados, neste momento, aos campi.<\/p>\n<p>A distribui\u00e7\u00e3o foi definida ap\u00f3s di\u00e1logo entre a Pr\u00f3-Reitoria de Planejamento e Desenvolvimento Institucional (PRD) e as Dire\u00e7\u00f5es-Gerais das unidades, considerando as necessidades previstas no Plano de Desenvolvimento Institucional (PDI).<\/p>\n<p>Os novos c\u00f3digos contemplam diferentes \u00e1reas do conhecimento e unidades do IFSP. As vagas abrangem \u00e1reas como Inform\u00e1tica, Letras, Matem\u00e1tica, Engenharia, Biologia, F\u00edsica, Qu\u00edmica, Educa\u00e7\u00e3o, Gest\u00e3o, Artes e diversas outras, de acordo com as demandas e os projetos de desenvolvimento de cada campus. Confira a distribui\u00e7\u00e3o completa no Comunicado n\u00b0 22\/2026.<\/p>\n<p><strong>Procedimentos para provimento<\/strong><\/p>\n<p>As unidades contempladas dever\u00e3o formalizar as solicita\u00e7\u00f5es de nomea\u00e7\u00e3o efetiva conforme as orienta\u00e7\u00f5es encaminhadas \u00e0s respectivas Dire\u00e7\u00f5es-Gerais. Caso seja necess\u00e1ria a altera\u00e7\u00e3o da \u00e1rea inicialmente indicada, a mudan\u00e7a dever\u00e1 ser justificada no requerimento de solicita\u00e7\u00e3o.<\/p>\n<p>De acordo com o comunicado, os pedidos de remo\u00e7\u00e3o ter\u00e3o prioridade sobre as demais formas de provimento das vagas, conforme estabelece a Portaria Normativa n\u00ba 114\/2024, que institui o Cadastro de Interesse em Remo\u00e7\u00e3o do IFSP.<\/p>\n<p>Ap\u00f3s a an\u00e1lise das remo\u00e7\u00f5es, a Diretoria de Gest\u00e3o de Pessoas (DGP) realizar\u00e1 a convoca\u00e7\u00e3o de candidatos aprovados em concursos p\u00fablicos vigentes do IFSP.<\/p>\n<p>Quando n\u00e3o houver concurso p\u00fablico vigente para determinada \u00e1rea, a DGP e a PRD poder\u00e3o avaliar a possibilidade de redistribui\u00e7\u00e3o ou a abertura de um novo concurso p\u00fablico. A previs\u00e3o \u00e9 de que o edital para um novo certame seja publicado at\u00e9 outubro de 2026.<\/p>\n<p>A defini\u00e7\u00e3o entre redistribui\u00e7\u00e3o e realiza\u00e7\u00e3o de concurso considerar\u00e1, entre outros fatores, a quantidade de servidores inscritos no Cadastro de Interesse de Redistribui\u00e7\u00e3o (CIRE) e o n\u00famero de vagas dispon\u00edveis na institui\u00e7\u00e3o.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Distribui\u00e7\u00e3o considera as necessidades previstas no Plano de Desenvolvimento Institucional; confira o\u00a0comunicado n\u00b0 22\/2026 O Instituto Federal de S\u00e3o Paulo (IFSP) iniciou a distribui\u00e7\u00e3o de novos c\u00f3digos de vaga para o cargo de Professor do Ensino B\u00e1sico, T\u00e9cnico e Tecnol\u00f3gico (EBTT). Ao todo, a institui\u00e7\u00e3o recebeu 180 novos c\u00f3digos por meio da Portaria MEC n\u00ba &#8230; <a title=\"IFSP distribui 165 novos c\u00f3digos de vaga para docentes entre os campi &#8211; IFSP\" class=\"read-more\" href=\"https:\/\/superinteressantes.com.br\/index.php\/2026\/09\/01\/ifsp-distribui-165-novos-codigos-de-vaga-para-docentes-entre-os-campi-ifsp\/\" aria-label=\"More on IFSP distribui 165 novos c\u00f3digos de vaga para docentes entre os campi &#8211; IFSP\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39937","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39937"}],"version-history":[{"count":0,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39937\/revisions"}],"wp:attachment":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}