{"id":39935,"date":"2026-09-01T18:51:17","date_gmt":"2026-09-01T21:51:17","guid":{"rendered":"https:\/\/superinteressantes.com.br\/index.php\/2026\/09\/01\/28a-festa-italiana-colonia-do-piagui-prefeitura-estancia-turistica-guaratingueta\/"},"modified":"2026-09-01T18:51:17","modified_gmt":"2026-09-01T21:51:17","slug":"28a-festa-italiana-colonia-do-piagui-prefeitura-estancia-turistica-guaratingueta","status":"publish","type":"post","link":"https:\/\/superinteressantes.com.br\/index.php\/2026\/09\/01\/28a-festa-italiana-colonia-do-piagui-prefeitura-estancia-turistica-guaratingueta\/","title":{"rendered":"28\u00aa Festa Italiana \u2013 Col\u00f4nia do Piagu\u00ed \u2013 Prefeitura Est\u00e2ncia Tur\u00edstica Guaratinguet\u00e1"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Prefeitura de Guaratinguet\u00e1 e a Associa\u00e7\u00e3o da Col\u00f4nia do Piagu\u00ed convidam toda a popula\u00e7\u00e3o para a 28\u00aa Festa Italiana da Col\u00f4nia do Piagu\u00ed, que acontece de 10 a 13 de setembro.\u00a0<\/p>\n<p>A abertura ser\u00e1 no dia 10 de setembro, a partir das 19h30, com a tradicional Missa em Italiano, celebrada por Dom M\u00e1rio Ant\u00f4nio da Silva, com participa\u00e7\u00e3o do Coral Decolores de Guaratinguet\u00e1, al\u00e9m da Trilogia de Ave Marias, com Thamy Quintanilha e Vin\u00edcius Guedes.<\/p>\n<p>Ap\u00f3s a missa, haver\u00e1 apresenta\u00e7\u00e3o da Tarantela Fiori d\u2019Napoli e Pra\u00e7a de Alimenta\u00e7\u00e3o com pratos t\u00edpicos.\u00a0<\/p>\n<p>\u00a0P\u00e1tio da Igreja S\u00e3o Jo\u00e3o Batista \u2013 Col\u00f4nia do Piagu\u00ed<\/p>\n<p>Confira no card a programa\u00e7\u00e3o da abertura da festa!<\/p>\n<p>Em breve, divulgaremos a programa\u00e7\u00e3o completa da festa.<\/p>\n<p>Venha celebrar conosco a cultura e as tradi\u00e7\u00f5es italianas!<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Guaratinguet\u00e1 e a Associa\u00e7\u00e3o da Col\u00f4nia do Piagu\u00ed convidam toda a popula\u00e7\u00e3o para a 28\u00aa Festa Italiana da Col\u00f4nia do Piagu\u00ed, que acontece de 10 a 13 de setembro.\u00a0 A abertura ser\u00e1 no dia 10 de setembro, a partir das 19h30, com a tradicional Missa em Italiano, celebrada por Dom M\u00e1rio Ant\u00f4nio &#8230; <a title=\"28\u00aa Festa Italiana \u2013 Col\u00f4nia do Piagu\u00ed \u2013 Prefeitura Est\u00e2ncia Tur\u00edstica Guaratinguet\u00e1\" class=\"read-more\" href=\"https:\/\/superinteressantes.com.br\/index.php\/2026\/09\/01\/28a-festa-italiana-colonia-do-piagui-prefeitura-estancia-turistica-guaratingueta\/\" aria-label=\"More on 28\u00aa Festa Italiana \u2013 Col\u00f4nia do Piagu\u00ed \u2013 Prefeitura Est\u00e2ncia Tur\u00edstica Guaratinguet\u00e1\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-39935","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=39935"}],"version-history":[{"count":0,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/39935\/revisions"}],"wp:attachment":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=39935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=39935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=39935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}