{"id":26115,"date":"2025-05-19T14:18:31","date_gmt":"2025-05-19T17:18:31","guid":{"rendered":"https:\/\/superinteressantes.com.br\/index.php\/2025\/05\/19\/agencia-minas-gerais-cemig-retira-36-toneladas-de-cabos-de-telecom-irregulares-de-postes-por-todo-o-estado\/"},"modified":"2025-05-19T14:18:31","modified_gmt":"2025-05-19T17:18:31","slug":"agencia-minas-gerais-cemig-retira-36-toneladas-de-cabos-de-telecom-irregulares-de-postes-por-todo-o-estado","status":"publish","type":"post","link":"https:\/\/superinteressantes.com.br\/index.php\/2025\/05\/19\/agencia-minas-gerais-cemig-retira-36-toneladas-de-cabos-de-telecom-irregulares-de-postes-por-todo-o-estado\/","title":{"rendered":"Ag\u00eancia Minas Gerais | Cemig retira 3,6 toneladas de cabos de telecom irregulares de\u00a0postes por todo o estado\u00a0"},"content":{"rendered":"<p><\/p>\n<div>\n<p>A Companhia Energ\u00e9tica de Minas Gerais (Cemig) est\u00e1 intensificando o combate aos cabos de empresas de telecom instalados irregularmente ou que n\u00e3o possuem contratos de compartilhamento nas estruturas da companhia.<\/p>\n<p>Somente nos tr\u00eas primeiros meses deste ano, a empresa j\u00e1 retirou 3,6 toneladas de fios irregulares em\u00a0postes em mais de 28 cidades do estado de Minas Gerais.<br \/>&#13;<br \/>\n\u00a0<\/p>\n<figure class=\"image\" style=\"float:left\">&#13;<figcaption><sub><em>Cemig \/ Divulga\u00e7\u00e3o<\/em><\/sub><\/figcaption>&#13;<br \/>\n<\/figure>\n<p>A gerente de Efici\u00eancia Energ\u00e9tica e Receitas Acess\u00f3rias da Cemig, Amanda Mascarenhas, detalha as a\u00e7\u00f5es para reduzir a quantidade de fios de telecomunica\u00e7\u00f5es irregulares nos postes da companhia.<\/p>\n<p>\u201cNo primeiro trimestre deste ano, os t\u00e9cnicos da Cemig j\u00e1 vistoriaram mais de 12 mil postes e retiraram a fia\u00e7\u00e3o de 19 empresas que atuavam de forma clandestina no sistema de distribui\u00e7\u00e3o da companhia. Nos \u00faltimos meses, a companhia tem refor\u00e7ado a notifica\u00e7\u00e3o das empresas que operam de forma irregular e trabalhado em conjunto com os munic\u00edpios para promover a\u00e7\u00f5es de conscientiza\u00e7\u00e3o que visam educar sobre os riscos e a necessidade de regulariza\u00e7\u00e3o\u201d, afirma.<\/p>\n<p>Nos quatro primeiros meses de 2025, a Cemig j\u00e1 fez 12.938 mil notifica\u00e7\u00f5es a empresas de telecom para realizar a adequa\u00e7\u00e3o de fia\u00e7\u00f5es em toda a sua \u00e1rea de concess\u00e3o. Esse n\u00famero j\u00e1 \u00e9 22,94% superior a todo o ano passado, quando foram realizadas 10.524 notifica\u00e7\u00f5es a empresas de processamentos de dados.<\/p>\n<p>O compartilhamento dos postes com as empresas de telefonia, internet e TV a cabo \u00e9 determinado pelas Resolu\u00e7\u00f5es Conjuntas 001\/1999 e 004\/2014, da Ag\u00eancia Nacional de Energia El\u00e9trica (Aneel), Ag\u00eancia Nacional de Telecomunica\u00e7\u00f5es (Anatel) e 1.044\/2022 da Aneel.<\/p>\n<p>&#8220;Essas resolu\u00e7\u00f5es estabelecem que as empresas respons\u00e1veis pelo processamento de dados devem cumprir os planos de ocupa\u00e7\u00e3o e as normas t\u00e9cnicas determinadas pela Cemig. Nos casos em que as empresas n\u00e3o realizam a regulariza\u00e7\u00e3o, a companhia tem tomado medidas diretas para eliminar os riscos, incluindo a retirada dos cabeamentos irregulares de seus postes&#8221;.<\/p>\n<p><strong>Modicidade tarif\u00e1ria<\/strong><\/p>\n<p>Al\u00e9m de levar servi\u00e7os b\u00e1sicos para a popula\u00e7\u00e3o, o compartilhamento dos postes com as empresas de telecomunica\u00e7\u00f5es contribui para a modicidade tarif\u00e1ria.<\/p>\n<p>De acordo com a legisla\u00e7\u00e3o do setor el\u00e9trico, 60% do valor faturado com este servi\u00e7o s\u00e3o utilizados para reduzir a fatura de energia, contribuindo com a modicidade tarif\u00e1ria.<\/p>\n<p>Recentemente, a Cemig concluiu o censo que identificou cabos de empresas que compartilham postes em sua \u00e1rea de concess\u00e3o. A companhia vistoriou cerca de 2,3 milh\u00f5es de postes em 774 munic\u00edpios mineiros e identificou a exist\u00eancia de mais de 900 empresas que operavam de forma clandestina, irregular e sem projetos, o que pode comprometer a resist\u00eancia mec\u00e2nica dos postes.\u00a0\u00a0<\/p>\n<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Companhia Energ\u00e9tica de Minas Gerais (Cemig) est\u00e1 intensificando o combate aos cabos de empresas de telecom instalados irregularmente ou que n\u00e3o possuem contratos de compartilhamento nas estruturas da companhia. Somente nos tr\u00eas primeiros meses deste ano, a empresa j\u00e1 retirou 3,6 toneladas de fios irregulares em\u00a0postes em mais de 28 cidades do estado de &#8230; <a title=\"Ag\u00eancia Minas Gerais | Cemig retira 3,6 toneladas de cabos de telecom irregulares de\u00a0postes por todo o estado\u00a0\" class=\"read-more\" href=\"https:\/\/superinteressantes.com.br\/index.php\/2025\/05\/19\/agencia-minas-gerais-cemig-retira-36-toneladas-de-cabos-de-telecom-irregulares-de-postes-por-todo-o-estado\/\" aria-label=\"More on Ag\u00eancia Minas Gerais | Cemig retira 3,6 toneladas de cabos de telecom irregulares de\u00a0postes por todo o estado\u00a0\">Ler mais<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-26115","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26115","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=26115"}],"version-history":[{"count":0,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/26115\/revisions"}],"wp:attachment":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=26115"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=26115"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=26115"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}