{"id":24859,"date":"2025-04-22T09:27:33","date_gmt":"2025-04-22T12:27:33","guid":{"rendered":"https:\/\/superinteressantes.com.br\/index.php\/2025\/04\/22\/sessao-de-sabado-exibe-hoje-19-04-na-globo-todo-poderoso-que-horas-comeca-sinopse\/"},"modified":"2025-04-22T09:27:33","modified_gmt":"2025-04-22T12:27:33","slug":"sessao-de-sabado-exibe-hoje-19-04-na-globo-todo-poderoso-que-horas-comeca-sinopse","status":"publish","type":"post","link":"https:\/\/superinteressantes.com.br\/index.php\/2025\/04\/22\/sessao-de-sabado-exibe-hoje-19-04-na-globo-todo-poderoso-que-horas-comeca-sinopse\/","title":{"rendered":"Sess\u00e3o de S\u00c1BADO exibe Hoje (19\/04) na Globo; Todo Poderoso, QUE HORAS COME\u00c7A, Sinopse"},"content":{"rendered":"<p> Por MRNews<br \/>\n<\/p>\n<div wp_automatic_readability=\"101.44924430408\">\n<p>COnfira a programa\u00e7\u00e3o da Globo\u00a0 <strong>hoje, 19\/04 <\/strong><strong>e que horas come\u00e7am os filmes de hoje.\u00a0<\/strong><\/p>\n<p><strong>Filmes na Globo \u2013 S\u00e1bado, 19 de abril de 2025: confira os destaques da programa\u00e7\u00e3o<\/strong><\/p>\n<p>Neste s\u00e1bado (19\/04), a TV Globo preparou uma sele\u00e7\u00e3o especial de filmes para agradar aos mais diversos gostos. Entre a\u00e7\u00e3o, guerra, com\u00e9dia e drama nacional, os destaques da programa\u00e7\u00e3o incluem t\u00edtulos internacionais e grandes sucessos do cinema brasileiro. Confira abaixo a programa\u00e7\u00e3o completa e os hor\u00e1rios previstos (de acordo com a grade tradicional da emissora):<\/p>\n<hr\/>\n<h3><strong>Coruj\u00e3o II \u2013 \u201c15 Minutos de Guerra\u201d<\/strong><\/h3>\n<p><strong>T\u00edtulo original:<\/strong> <em>15 Minutes of War<\/em><br \/><strong>Hor\u00e1rio previsto:<\/strong> madrugada de sexta para s\u00e1bado<br \/><strong>Pa\u00eds de origem:<\/strong> B\u00e9lgica<br \/><strong>Ano:<\/strong> 2019<br \/><strong>G\u00eanero:<\/strong> A\u00e7\u00e3o \/ Guerra<br \/><strong>Dire\u00e7\u00e3o:<\/strong> Fred Grivois<br \/><strong>Elenco:<\/strong> Alban Lenoir, David Murgia, Olga Kurylenko, Michael Abiteboul<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2025\/04\/19\/quais-filmes-vao-passar-segunda-21-04-na-globo-corujao-sessao-da-tarde-e-tela-quente-que-horas-comeca-sinopse\/\">Quais filmes v\u00e3o passar Segunda (21\/04) na Globo? CORUJ\u00c3O, SESS\u00c3O DA TARDE E TELA QUENTE \u2013 QUE HORAS COME\u00c7A, Sinopse<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2025\/04\/19\/quais-filmes-vao-passar-hoje-20-04-na-globo-temperatura-maxima-cinemaco-e-domingo-maior-corujao-que-horas-comeca-sinopse\/\">Quais Filmes v\u00e3o passar HOJE (20\/04) na Globo? TEMPERATURA M\u00c1XIMA, CINEMA\u00c7O E DOMINGO MAIOR, CORUJ\u00c3O; QUE HORAS COME\u00c7A, Sinopse<\/a><\/strong><\/p>\n<p>Baseado em uma hist\u00f3ria real, o longa se passa em <strong>fevereiro de 1976<\/strong>, em <strong>Djibouti<\/strong>, quando um \u00f4nibus escolar \u00e9 sequestrado por terroristas na fronteira com a Som\u00e1lia. O governo franc\u00eas envia ent\u00e3o o <strong>GIGN<\/strong>, uma unidade de elite, para liderar uma arriscada opera\u00e7\u00e3o de resgate. O filme traz tens\u00e3o, estrat\u00e9gia militar e emo\u00e7\u00e3o do in\u00edcio ao fim.<\/p>\n<hr\/>\n<h3><strong>Sess\u00e3o de S\u00e1bado \u2013 \u201cTodo Poderoso\u201d<\/strong><\/h3>\n<p><strong>T\u00edtulo original:<\/strong> <em>Bruce Almighty<\/em><br \/><strong>Hor\u00e1rio previsto:<\/strong> 14h10 (ap\u00f3s o Jornal Hoje)<br \/><strong>Pa\u00eds de origem:<\/strong> Estados Unidos<br \/><strong>Ano:<\/strong> 2003<br \/><strong>G\u00eanero:<\/strong> Com\u00e9dia<br \/><strong>Dire\u00e7\u00e3o:<\/strong> Tom Shadyac<br \/><strong>Elenco:<\/strong> Jim Carrey, Jennifer Aniston, Morgan Freeman<\/p>\n<p>Um dos maiores sucessos da carreira de <strong>Jim Carrey<\/strong>, o filme conta a hist\u00f3ria de Bruce, um rep\u00f3rter frustrado que vive reclamando de tudo \u2014 inclusive de Deus. At\u00e9 que o pr\u00f3prio Todo-Poderoso, interpretado por Morgan Freeman, lhe concede seus poderes por uma semana. Com\u00e9dia com reflex\u00f5es e muitas risadas garantidas.<\/p>\n<hr\/>\n<h3><strong>Supercine \u2013 \u201cDe Pernas Pro Ar 3\u201d<\/strong><\/h3>\n<p><strong>T\u00edtulo original:<\/strong> <em>De Pernas Pro Ar 3<\/em><br \/><strong>Hor\u00e1rio previsto:<\/strong> ap\u00f3s o Altas Horas<br \/><strong>Pa\u00eds de origem:<\/strong> Brasil<br \/><strong>Ano:<\/strong> 2019<br \/><strong>G\u00eanero:<\/strong> Com\u00e9dia<br \/><strong>Dire\u00e7\u00e3o:<\/strong> J\u00falia Rezende<br \/><strong>Elenco:<\/strong> Ingrid Guimar\u00e3es, Maria Paula, Bruno Garcia, Denise Weinberg<\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2025\/04\/19\/corujao-exibe-hoje-sabado-19-04-na-globo-domingo-que-horas-comeca-sinopse\/\">Coruj\u00e3o exibe Hoje, S\u00e1bado (19\/04) na Globo; Domingo , QUE HORAS COME\u00c7A, Sinopse<\/a><\/strong><\/p>\n<p><strong><a href=\"https:\/\/mrnews.com.br\/index.php\/2025\/04\/19\/supercine-exibe-hoje-sabado-19-04-na-globo-de-pernas-pro-ar-3-que-horas-comeca-sinopse\/\">Supercine exibe Hoje, S\u00e1bado (19\/04) na Globo; De Pernas Pro Ar 3, QUE HORAS COME\u00c7A, Sinopse<\/a><\/strong><\/p>\n<p>No terceiro filme da franquia de sucesso, <strong>Alice<\/strong> (Ingrid Guimar\u00e3es) expande seu imp\u00e9rio de lojas er\u00f3ticas e embarca numa turn\u00ea internacional. No entanto, sua dedica\u00e7\u00e3o ao trabalho a distancia da fam\u00edlia, fazendo com que ela repense suas prioridades. Divers\u00e3o nacional com toque de cr\u00edtica social sobre a mulher moderna.<\/p>\n<hr\/>\n<h3><strong>Coruj\u00e3o I \u2013 \u201cDomingo\u201d<\/strong><\/h3>\n<p><strong>T\u00edtulo original:<\/strong> <em>Domingo<\/em><br \/><strong>Hor\u00e1rio previsto:<\/strong> madrugada de s\u00e1bado para domingo<br \/><strong>Pa\u00eds de origem:<\/strong> Brasil<br \/><strong>Ano:<\/strong> 2020<br \/><strong>G\u00eanero:<\/strong> Drama<br \/><strong>Dire\u00e7\u00e3o:<\/strong> Clara Linhart, Felipe Gamarano Barbosa<br \/><strong>Elenco:<\/strong> Augusto Madeira, Camila Morgado, Chay Suede, \u00cdtala Nandi<\/p>\n<p>No interior do Rio Grande do Sul, uma fam\u00edlia da elite vive um tenso dia 1\u00ba de janeiro de 2003 \u2014 data da posse do ex-presidente Lula. Em meio a jantares, discursos e confrontos, segredos v\u00eam \u00e0 tona, revelando as fragilidades das apar\u00eancias. Um drama pol\u00edtico e familiar que explora rela\u00e7\u00f5es de poder e classe social.<\/p>\n<hr\/>\n<p><strong>Tags:<\/strong> #FilmesNaGlobo #Sess\u00e3oDeS\u00e1bado #Coruj\u00e3o #Supercine #CinemaEmCasa #TodoPoderoso #DePernasProAr3 #15MinutosDeGuerra #Domingo<\/p>\n<div wp_automatic_readability=\"6.8256880733945\">\n<p>Para mais detalhes, acesse os portais da Globo:<\/p>\n<ul>\n<li><a href=\"https:\/\/espigaoalerta.com.br\" target=\"_blank\" rel=\"noopener\">G1<\/a> \u2013 Not\u00edcias atualizadas<\/li>\n<li><a href=\"https:\/\/brazilsoccer.com.br\" target=\"_blank\" rel=\"noopener\">ge<\/a> \u2013 Esportes<\/li>\n<li><a href=\"https:\/\/jblog.com.br\" target=\"_blank\" rel=\"noopener\">gshow<\/a> \u2013 Entretenimento e TV<\/li>\n<li><a href=\"https:\/\/sentoseagora.com.br\" target=\"_blank\" rel=\"noopener\">Globoplay<\/a> \u2013 Streaming de conte\u00fado Globo<\/li>\n<li><a href=\"https:\/\/ojornaldebatatais.com.br\" target=\"_blank\" rel=\"noopener\">Mem\u00f3ria Globo<\/a> \u2013 Arquivo hist\u00f3rico da emissora<\/li>\n<\/ul>\n<p>\u00a0<\/p>\n<\/div>\n<p><!-- CONTENT END 3 --><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Por MRNews COnfira a programa\u00e7\u00e3o da Globo\u00a0 hoje, 19\/04 e que horas come\u00e7am os filmes de hoje.\u00a0 Filmes na Globo \u2013 S\u00e1bado, 19 de abril de 2025: confira os destaques da programa\u00e7\u00e3o Neste s\u00e1bado (19\/04), a TV Globo preparou uma sele\u00e7\u00e3o especial de filmes para agradar aos mais diversos gostos. Entre a\u00e7\u00e3o, guerra, com\u00e9dia e &#8230; <a title=\"Sess\u00e3o de S\u00c1BADO exibe Hoje (19\/04) na Globo; Todo Poderoso, QUE HORAS COME\u00c7A, Sinopse\" class=\"read-more\" href=\"https:\/\/superinteressantes.com.br\/index.php\/2025\/04\/22\/sessao-de-sabado-exibe-hoje-19-04-na-globo-todo-poderoso-que-horas-comeca-sinopse\/\" aria-label=\"More on Sess\u00e3o de S\u00c1BADO exibe Hoje (19\/04) na Globo; Todo Poderoso, QUE HORAS COME\u00c7A, Sinopse\">Ler mais<\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-24859","post","type-post","status-publish","format-standard","hentry","category-sem-categoria"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=24859"}],"version-history":[{"count":0,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/posts\/24859\/revisions"}],"wp:attachment":[{"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=24859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=24859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/superinteressantes.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=24859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}